{"id":2899,"date":"2021-08-10T10:33:27","date_gmt":"2021-08-10T08:33:27","guid":{"rendered":"https:\/\/mainperformance.de\/?p=2899"},"modified":"2023-06-09T09:27:28","modified_gmt":"2023-06-09T07:27:28","slug":"immunfunktion-2","status":"publish","type":"post","link":"https:\/\/mainperformance.de\/en\/immunfunktion-2\/","title":{"rendered":"Mit diesen Ern\u00e4hrungsprinzipien optimierst Du deine Immunfunktion"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2899\" class=\"elementor elementor-2899\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a5b0a98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a5b0a98\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7641eef5\" data-id=\"7641eef5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1386f0b2 elementor-widget elementor-widget-text-editor\" data-id=\"1386f0b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">In Zeiten des Corona Virus kommt es bei vielen zu Unsicherheiten. Aufgrund von grippalen Symptomen, m\u00fcssen einige Menschen ihren Alltag komplett umstrukturieren. Im Falle einer COVID-19 Erkrankung oder einer Grippe, schaltet sich dein Immunsystem ein und ist daf\u00fcr verantwortlich, diese Erreger zu bek\u00e4mpfen.<\/span><\/p><p>\u00a0<\/p><p><span data-contrast=\"auto\">Eine Ma\u00dfnahme, welche Du ergreifen kannst, um dich zu sch\u00fctzen und eine optimale <strong>Immunfunktion<\/strong> zu gew\u00e4hrleisten, besteht darin, dich so gesund wie m\u00f6glich zu ern\u00e4hren. (1)<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Der ideale <a title=\"Ern\u00e4hrungsumstellung\" href=\"\/en\/ernaehrungsumstellung\/\">Ern\u00e4hrungsplan<\/a>, f\u00fcr deine optimale <strong>Immunfunktion<\/strong>, sollte 3 Faktoren beinhalten:<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1. Optimiere deinen Blutzucker<\/span><\/p><p>\u00a0<\/p><p>Es ist bekannt, dass Hyperglyk\u00e4mie bzw. ein dauerhaft erh\u00f6hter Blutzucker, die wei\u00dfen Blutk\u00f6rperchen deines Immunsystems negativ beeinflusst. Dies hat zur Folge, dass Personen mit hohem Blutzucker anf\u00e4lliger f\u00fcr Infektionen sind. Gerade in der aktuellen Thematik, ist immer wieder zur Sprache gekommen, dass Diabetiker mit gr\u00f6\u00dferer Wahrscheinlichkeit gef\u00e4hrliche Komplikationen nach einer Corona Infizierung haben.\u00a0<span data-ccp-props=\"{\">\u00a0<\/span><\/p><p>\u00a0<\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2. Schenke deinem Darm mehr Aufmerksamkeit <\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Die Unterst\u00fctzung deiner Magen-Darm-Gesundheit ist von entscheidender Bedeutung, da sich etwa 70 Prozent deiner Immunzellen im Darm befinden. Au\u00dferdem sitzt im Darm auch ein Gro\u00dfteil deines Lymphsystems, das eine zentrale Rolle bei der Verteidigung deines K\u00f6rpers gegen Viren, Bakterien und fremde Krankheitserreger spielt (2).<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 3. Achte auf ein m\u00f6glichst breites N\u00e4hrstoffspektrum<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Jede gesunde Ern\u00e4hrungsform sollte auf einer Vielzahl von verschiedenen Lebensmitteln basieren, welche Dir die reichlich vorhandenen N\u00e4hrstoffe liefern, die dein K\u00f6rper ben\u00f6tigt. Diese braucht er, um Entz\u00fcndungen zu bek\u00e4mpfen und Krankheiten abzuwehren (3).<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><strong>Befolge die unten aufgelisteten Punkte, um dein Immunsystem mit einfachen Prinzipien und Gewohnheiten zu unterst\u00fctzen. \u00a0<\/strong><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1. Versuche zu jeder Mahlzeit Protein, etwas Fett und Gem\u00fcse zu essen<\/span><\/p><p>\u00a0<\/p><p>Diese Kombination sollte deine erste Wahl sein, um den Blutzucker zu regulieren und die Magen Darm Funktion zu f\u00f6rdern. Hochwertiges Protein liefert die f\u00fcr die Heilung notwendigen Bausteine \u200b\u200bund wird zum Aufbau von Antik\u00f6rpern und Immunzellen verwendet. Achte auf eine Vielzahl von proteinhaltigen Lebensmitteln, wie beispielsweise Meeresfr\u00fcchte, Fleisch, Gefl\u00fcgel, Eier, H\u00fclsenfr\u00fcchte, Milchprodukte, N\u00fcsse und Samen.<\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2. Achte auf ausreichend gesunde Fette<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Fett ist nicht gleich Fett. Verschiedene Formen verursachen beispielsweise Entz\u00fcndungen und beeintr\u00e4chtigen die <strong>Immunfunktion<\/strong>. Darunter Transfetts\u00e4uren und Omega-6-Fette, welche in Samen\u00f6len reichlich vorhanden sind. Im Gegensatz dazu unterst\u00fctzen sogenannte Omega-3-Fetts\u00e4uren bspw. aus Fisch\u00f6l und die einfach unges\u00e4ttigten Fette, welche in N\u00fcssen vorkommen, die Gesundheit deines Immunsystems.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 3. Konzentriere dich auf buntes Gem\u00fcse und Obst<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Jede gesunde Ern\u00e4hrung sollte buntes Obst und Gem\u00fcse beinhalten, dass die reichlich vorhandenen Phyton\u00e4hrstoffe liefert, die dein K\u00f6rper ben\u00f6tigt, um Krankheiten abzuwehren. Pflanzliche Lebensmittel liefern auch pr\u00e4biotische Ballaststoffe, welche die gesunden Bakterien in deinem Darm ern\u00e4hren. Konzentriere dich also darauf, nach dem \u201eRegenbogen Prinzip\u201c zu essen, und nimm so viel Blattgem\u00fcse, gr\u00fcne, rote, gelbe, orange und violette Lebensmittel wie m\u00f6glich auf.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 4. Vermeide die \u00fcblichen Verd\u00e4chtigen<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Zucker, verarbeitete und raffinierte Lebensmittel sollten vermieden werden, da sie den Blutzuckerspiegel erh\u00f6hen und die Teile deines Gehirns stimulieren, welche zu \u00fcberm\u00e4\u00dfigem Essen anregen. Meist haben sie noch dazu, einen geringen N\u00e4hrwert und liefern nicht die Bausteine, die f\u00fcr eine robuste <strong>Immunfunktion<\/strong> erforderlich sind.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 5. Behalte deinen Kalorienbedarf im Blick<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Eine gesunde K\u00f6rperzusammensetzung kommt der Funktion deines Immunsystems zugute. Fettleibigkeit ist eine entz\u00fcndliche Erkrankung, die mit einem erh\u00f6hten Risiko f\u00fcr grippale Infekte und andere Erkrankungen wie Lungenentz\u00fcndung in Verbindung gebracht wurde (3).<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 6. Unterst\u00fctze deine gesunde Lebensweise durch Nahrungserg\u00e4nzungsmittel<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Es kann von Vorteil sein, <a title=\"Nahrungserg\u00e4nzungsmittel\" href=\"\/en\/nahrungsergaenzungsmittel\/\">Nahrungserg\u00e4nzungsmittel<\/a> einzubauen, welche das Ziel haben, N\u00e4hrstoffm\u00e4ngel auszugleichen. Wichtig dabei ist, dass die N\u00e4hrstoffe in ihrer bioverf\u00fcgbarsten Form bereitgestellt werden. Zink ist beispielsweise ein Top-Supplement zur Unterst\u00fctzung des Immunsystems, aber weniger als 40 Prozent der Bev\u00f6lkerung erhalten die empfohlene Menge (NHANES) (5). Auch bei ausreichender Zufuhr kommt es h\u00e4ufig zu einem Mangel an pflanzlichen Nahrungsbestandteilen, die die Aufnahme von Zink und anderen Mineralstoffen beeintr\u00e4chtigen.<\/span><\/p><p>\u00a0<\/p><p><span data-contrast=\"auto\">Nahrungserg\u00e4nzungsmittel sind kein Wundermittel, k\u00f6nnen aber, wenn die Basis stimmt, zu einem gro\u00dfen Schritt in die richtige Richtung beitragen.<\/span><\/p><p>\u00a0<\/p><p><span data-contrast=\"auto\">Die Ern\u00e4hrung stellt ein m\u00e4chtiges Werkzeug dar, mit der du gro\u00dfen Einfluss auf die Funktion deines Immunsystems haben kannst. Befolge diese Tipps, um dein Immunsystem im Falle einer Erkrankung zu unterst\u00fctzen oder Dich<\/span><span data-contrast=\"auto\"> pr\u00e4ventiv zu sch\u00fctzen.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p>\u00a0<\/p><p><span data-contrast=\"none\">Quellenangaben:<\/span><\/p><p><span data-contrast=\"none\">1. Beck, M., et al. <\/span><span data-contrast=\"none\">Host nutritional status: the neglected virulence factor. Trends in Microbiology. 2004. 12(9), 417-423.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">2. Cooper, E., Ma, M. Understanding nutrition and immunity in disease management. Journal of Traditional and Complementary Medicine. 2017. 7(4): 386\u2013391.<\/span><\/p><p>3. Alwarawrah, Y., et al. Changes in nutritional status impact immune cell metabolism and function. Frontiers in Immunology. 2018. 9: 1055-1069.<\/p><p>4. National Institute of Allergy and Infectious Diseases. Overview of the Immune System. Retrieved March 29, 2020. https:\/\/www.niaid.nih.gov\/research\/immune-system-overview.<\/p><p><span data-contrast=\"none\">5. Moshfegh A, Goldman J, Ahuja J, et al. What We Eat in America, NHANES 2005-2006: Usual Nutrient Intakes from Food and Water Compared to 1997 Dietary Reference Intakes for Vitamin D, Calcium, Phosphorus, and Magnesium. <\/span><span data-contrast=\"none\">2009. U.S. Department of Agriculture, Agricultural Research Service.<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>In Zeiten des Corona Virus kommt es bei vielen zu Unsicherheiten. Aufgrund von grippalen Symptomen, m\u00fcssen einige Menschen ihren Alltag komplett umstrukturieren. Im Falle einer COVID-19 Erkrankung oder einer Grippe, schaltet sich dein Immunsystem ein und ist daf\u00fcr verantwortlich, diese Erreger zu bek\u00e4mpfen. \u00a0 Eine Ma\u00dfnahme, welche Du ergreifen kannst, um dich zu sch\u00fctzen und [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2901,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-2899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit-und-ernahrung"],"_links":{"self":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/2899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/comments?post=2899"}],"version-history":[{"count":0,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/2899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media\/2901"}],"wp:attachment":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media?parent=2899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/categories?post=2899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/tags?post=2899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}