{"id":3340,"date":"2021-10-13T09:39:20","date_gmt":"2021-10-13T07:39:20","guid":{"rendered":"https:\/\/mainperformance.de\/?p=3340"},"modified":"2023-06-09T09:26:45","modified_gmt":"2023-06-09T07:26:45","slug":"ernaehrst-du-dich-wirklich-so-gut-wie-du-denkst","status":"publish","type":"post","link":"https:\/\/mainperformance.de\/en\/ernaehrst-du-dich-wirklich-so-gut-wie-du-denkst\/","title":{"rendered":"Ern\u00e4hrst Du Dich wirklich so gut, wie Du denkst?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3340\" class=\"elementor elementor-3340\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05d3907 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05d3907\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afbf0bc\" data-id=\"afbf0bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-508f44b elementor-widget elementor-widget-text-editor\" data-id=\"508f44b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"auto\">Ern\u00e4hrst Du Dich wirklich so gut, wie Du denkst?<\/span><\/b><span data-ccp-props=\"{\">\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Die Ern\u00e4hrung ist ein gro\u00dfes, dogmatisches und emotionales Thema.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">In diesem Artikel werde ich dir einige grundlegende und bew\u00e4hrte Prinzipien zeigen, welche dir durch hilfreiche Tricks und Tipps einen klareren Weg im Dschungel der vielen Ern\u00e4hrungsmythen aufzeigen sollen.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Schlie\u00dflich kann die Person, die Prinzipien versteht, erfolgreich ihre eigenen Methoden ausw\u00e4hlen. <\/span>\u00a0<\/p><p><span data-contrast=\"none\">Die Person, die Methoden nur ausprobiert, ohne die Prinzipien zu verstehen, wird mit Sicherheit Probleme haben.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><b style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\"><span data-contrast=\"none\">Die Schl\u00fcsselelemente einer guten Ern\u00e4hrung<\/span><\/b><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Wir m\u00f6chten dir vorab einige allgemein g\u00fcltige Dinge mitgeben, welche als Grundlage angesehen werden k\u00f6nnen.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><ol><li data-leveltext=\"%1.\" data-font=\"Calibri,Times New Roman\" data-listid=\"1\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Der beste Ern\u00e4hrungsplan ist der, an den du dich halten kannst.<\/span>\u00a0<\/li><li data-leveltext=\"%1.\" data-font=\"Calibri,Times New Roman\" data-listid=\"1\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Kalorien sind wichtig f\u00fcr K\u00f6rperkomposition und Leistungsf\u00e4higkeit.<\/span><\/li><li data-leveltext=\"%1.\" data-font=\"Calibri,Times New Roman\" data-listid=\"1\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Um Fett zu verlieren, iss weniger Kalorien als du verbrauchst.<\/span>\u00a0<\/li><li data-leveltext=\"%1.\" data-font=\"Calibri,Times New Roman\" data-listid=\"1\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Um Muskeln aufzubauen, iss mehr Protein und trainiere 3-4x\/ Woche.<\/span>\u00a0<\/li><li data-leveltext=\"%1.\" data-font=\"Calibri,Times New Roman\" data-listid=\"1\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Um deine aktuelle Situation aufrechtzuerhalten: Passe deinen Kalorienbedarf an deinen Kalorienverbrauch an.<\/span>\u00a0<\/li><li data-leveltext=\"%1.\" data-font=\"Calibri,Times New Roman\" data-listid=\"1\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Der Proteinkonsum kann die K\u00f6rperzusammensetzung beeinflussen. Iss genug davon, um deinen K\u00f6rper zu ver\u00e4ndern, nicht nur um zu \u00fcberleben.<\/span>\u00a0<\/li><li data-leveltext=\"%1.\" data-font=\"Calibri,Times New Roman\" data-listid=\"1\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Solange du die richtige Menge an Gesamtkalorien und Protein f\u00fcr dein Ziel isst, spielt das Verh\u00e4ltnis von Kohlenhydraten zu Fetten keine Rolle. Es sei denn, du hast ein sportspezifisches Ziel oder eine einzigartige Erkrankung.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/li><\/ol><div>\u00a0<\/div><div><b>\u00a0<\/b><\/div><div><span style=\"font-weight: bold; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\">Es gibt keine guten oder schlechten Lebensmittel<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\">\u00a0<\/span><b><br \/><\/b><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\"><br \/><\/span><\/div><p><span data-contrast=\"none\">Wir k\u00f6nnen das nicht oft genug betonen. Betrachte Lebensmittel nicht als gut oder schlecht, sondern als &#8222;Gibt es derzeit eine bessere Option, um meinen Bed\u00fcrfnissen gerecht zu werden?&#8220;<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Ein gutes Beispiel daf\u00fcr ist Reis.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Reis als Grundnahrungsmittel enth\u00e4lt nicht viele N\u00e4hrstoffe, hat einen geringen Anteil an Ballaststoffen und eine moderate Menge an Kalorien aus Kohlenhydraten.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">F\u00fcr eine kleinere Frau, die K\u00f6rperfett verlieren m\u00f6chte, bietet Reis nicht viel. Die Kalorien in Reis k\u00f6nnten besser f\u00fcr Gem\u00fcse und Fleisch \u201eausgegeben\u201c werden, welche mehr Protein, Vitamine und Ballaststoffe f\u00fcr weniger Kalorien bieten.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Gem\u00fcse w\u00e4re f\u00fcr diese Person eine \u201ebessere\u201c Option als Reis.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Ein Tour De France-Radfahrer ben\u00f6tigt jedoch Kalorien aus einer Quelle, die leicht verdaulich ist und in gro\u00dfen Mengen verzehrt werden kann. Reis passt perfekt zu dieser Rechnung.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Unteranderem war Reis ein Grundnahrungsmittel von Lance Armstrong, welcher mehrmals die Tour De France gewann.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><b style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\"><span data-contrast=\"none\">Die Qualit\u00e4t ist entscheidend<\/span><\/b><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Ja, du kannst mit einer McDonald&#8217;s-Di\u00e4t abnehmen. Dies bedeutet jedoch nicht, dass wir dies empfehlen.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Die \u201eQualit\u00e4t\u201c eines Lebensmittels kann als die Menge an N\u00e4hrstoffen angesehen werden, die es pro Kalorie enth\u00e4lt.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">N\u00e4hrstoffreiche, kalorienarme Optionen wie Gem\u00fcse und mageres Fleisch sind eine hervorragende Grundlage f\u00fcr eine gute Ern\u00e4hrung, weil du mehr davon essen kannst und es dich l\u00e4nger satt h\u00e4lt.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><b style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\"><span data-contrast=\"none\">Was bedeutet Qualit\u00e4t?<\/span><\/b><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size );\" data-contrast=\"none\">Konsumiere so viele \u201eechte Lebensmittel\u201c wie m\u00f6glich.\u00a0<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size );\" data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Als Faustregel gilt: &#8222;Wenn es gelaufen, geschwommen oder gewachsen ist- iss es!\u201c<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">W\u00e4hle nach M\u00f6glichkeit grasgef\u00fctterte oder biologische Optionen und priorisiere Lebensmittel mit einem hohem N\u00e4hrstoff- und Fasergehalt. Gem\u00fcse ist das Essen der Champions!<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Einfach gesagt:<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><i><span data-contrast=\"none\">&#8222;Iss Fleisch, Gem\u00fcse, N\u00fcsse und Samen, etwas Obst, wenig St\u00e4rke, keinen Zucker! Halte die Essensaufnahme auf einem Niveau, das Bewegung unterst\u00fctzt, aber nicht K\u00f6rperfett. &#8222;<\/span><\/i>\u00a0<br \/><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><b style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\"><span data-contrast=\"none\">Solltest du Kalorien z\u00e4hlen oder nicht?<\/span><\/b><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Wir liefern dir deine t\u00e4glichen Kalorien- und Makron\u00e4hrstoffziele basierend auf deinen aktuellen Messungen und Zielen.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Kalorienz\u00e4hlen mit einer K\u00fcchenwaage und einer App wie bspw. \u201eMyFitnessPal\u201c funktioniert unglaublich gut &#8211; wenn du es tust. <\/span><\/p><p><span data-contrast=\"none\">Es wird zu Beginn sehr zeitaufw\u00e4ndig sein und es kann einige Zeit dauern, bis du dich daran gew\u00f6hnt hast. In bestimmten Situationen, f\u00fcr einen gewissen Zeitraum, kann es sich durchaus lohnen, um ein paar &#8222;Woah!&#8220; und &#8222;a-ha!&#8220; Momente zu bekommen.<\/span>\u00a0<br \/><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Wichtig f\u00fcr dich zu wissen ist, dass nur ca. 10 % unserer Kunden (und weniger als 5% der Gesamtbev\u00f6lkerung) sich jemals die M\u00fche machen, dies tats\u00e4chlich zu tun &#8211; aber sie erzielen gro\u00dfartige Ergebnisse. <\/span>\u00a0<br \/><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Deine Hausaufgabe Nr. 1<\/span><\/b><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Wenn du sehr engagiert bist und deine Kalorienaufnahme am Tag zu \u00fcberwachen m\u00f6chtest, haben wir eine Hausaufgabe f\u00fcr dich:<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Nimm deine Daten aus der letzten K\u00f6rperanalyse herunter und gib diese in MyFitnessPal ein. Falls die letzte Messung schon etwas her ist, spreche uns gerne jederzeit darauf an!<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Investiere in eine Lebensmittelwaage und f\u00fcge jeden Tag, deine Lebensmittel hinzu, mit dem Ziel, dein Kalorien- und mindestens 90% deines Proteinziels zu erreichen.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-contrast=\"none\">I<\/span><b style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\"><span data-contrast=\"none\">ch m\u00f6chte aber keine Kalorien z\u00e4hlen!<\/span><\/b><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Wenn du zu den verbleibenden 90% der Bev\u00f6lkerung geh\u00f6rst und nicht alles wiegen und messen m\u00f6chtest, was du isst, ist das \u00fcberhaupt kein Problem.<\/span>\u00a0<\/p><p><span data-contrast=\"none\">Dies bedeutet NICHT, dass du keine gro\u00dfartigen Ergebnisse erzielen kannst!<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Anschlie\u00dfend, geben wir dir ein paar Tipps, welche du nicht von Anfang an alle umsetzen musst. Geh stattdessen mit der Einstellung heran &#8222;Was kann ich diese Woche \/ zwei Wochen ERFOLGREICH erreichen?&#8220; und ziele auf Entscheidungen ab, die \u201enur ein bisschen besser\u201c sind als zuvor.<\/span>\u00a0<br \/><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">1. Tausche jeden Tag ein kalorienreiches Lebensmittel gegen ein kalorienarmes Lebensmittel aus<\/span>\u00a0<br \/><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Im Wesentlichen sollte dies eine langfristige Ern\u00e4hrung sein &#8211; schrittweise weniger geeignete Lebensmittel gegen besser geeignete Lebensmittel austauschen. Tausche ein alkoholisches Getr\u00e4nk gegen ein Glas Wasser. Tausche das R\u00fchrei gegen das Croissant. Versuche es mit Putenbrust anstelle von Speckstreifen.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a02.\u00a0<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-contrast=\"none\">Versuche dein Essen am Tag vorauszuplanen<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family );\" data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Essen im Restaurant und Essen zum Mitnehmen f\u00fchrt schnell dazu, dass mehr Kalorien gegessen werden als die eigentliche Vorgabe.<\/span>\u00a0<\/p><p><span data-contrast=\"none\">Beginne damit, ein paar Fr\u00fchst\u00fccksoptionen zu finden, welche dir schmecken, um unter der Woche vorbereitet zu sein. Als n\u00e4chstes kannst du versuchen, auch dein Mittag- und Abendessen vorzubereiten, indem du die richtigen Zutaten einkaufst und dir Gedanken machst, was du n\u00e4chste Woche essen k\u00f6nntest.<\/span>\u00a0<\/p><p><span data-contrast=\"none\">Du wirst schnell feststellen, dass dies viel Geld spart. Eine Mahlzeit weniger zum Mitnehmen pro Woche macht hier bereits einen gro\u00dfen Unterschied.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">3. \u00dcbe \u201eEssenshygiene\u201c<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Nimm dir Zeit, dich ungest\u00f6rt hinzusetzen und zu essen. Lege deine Gabel zwischen den Bissen ab, kaue dein Essen gr\u00fcndlich und ruh dich aus und verdaue. Keine Telefone, keine Laptops. Nur du, eine sch\u00f6ne gesunde Mahlzeit und f\u00fcnfzehn Minuten f\u00fcr dich.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">4. Achtsamkeit<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Frage dich bei jeder Mahlzeit, die du isst: &#8222;Was habe ich an der Mahlzeit bemerkt?&#8220; <\/span>\u00a0<\/p><p><span data-contrast=\"none\">Hast du etwas \u00fcber den Geschmack, die Textur, die Salzigkeit oder die S\u00e4ure des Essens bemerkt? Warst du \u00fcberhaupt hungrig oder hast du nur aus Langeweile oder Lust gegessen?<\/span>\u00a0<\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">5. Der perfekte Teller<\/span><span data-ccp-props=\"{\">\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><ul><li data-leveltext=\"-\" data-font=\"Calibri\" data-listid=\"4\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"none\">\u00bd Teller gr\u00fcnes Gem\u00fcse\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/li><li data-leveltext=\"-\" data-font=\"Calibri\" data-listid=\"4\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"none\">\u00bc Teller mageres Protein<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/li><li data-leveltext=\"-\" data-font=\"Calibri\" data-listid=\"4\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"none\">\u00bc Teller hochwertige Kohlenhydrate<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/li><\/ul><p><span data-contrast=\"none\">Halte es m\u00f6glichst einfach. Wenn du den oben aufgelisteten Portionen noch einer daumengro\u00dfen Portion an gesunden Fetten hinzuf\u00fcgst, erh\u00e4ltst du eine wunderbare, gesunde und n\u00e4hrstoffreiche Mahlzeit. <\/span>\u00a0<br \/><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Iss t\u00e4glich zwei bis vier dieser Mahlzeiten, je nach Zielsetzung und passe sie dann an deine Bed\u00fcrfnisse und deinen Lebensstil an. <\/span>\u00a0<\/p><p><span data-contrast=\"none\">Halte Ausnahmen auf ein Minimum, aber nicht auf null! Du bist ein Mensch, du willst ein soziales Leben und du lebst nur einmal.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Deine Hausaufgabe Nr. 2<\/span><\/b><span data-ccp-props=\"{\">\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Damit du die oben genannten Tipps gut umsetzen kannst, haben wir hier noch eine Hausaufgabe f\u00fcr dich:<\/span> \u00a0<\/p><p><span data-contrast=\"none\">Schreibe heute eine Sache auf, von der du wei\u00dft, dass du sie jetzt im Moment \u00e4ndern kannst, um deine Ern\u00e4hrung zu verbessern und diese Woche umzusetzen.<\/span>\u00a0<\/p><p><span data-contrast=\"none\">Nimm dir ab heute au\u00dferdem, jeden Tag mindestens einmal die Zeit, dich zu einer ungest\u00f6rten Mahlzeit zu setzen. Versuche dabei bewusst, auf eine Sache bei dieser Mahlzeit achten.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ern\u00e4hrst Du Dich wirklich so gut, wie Du denkst? Die Ern\u00e4hrung ist ein gro\u00dfes, dogmatisches und emotionales Thema. In diesem Artikel werde ich dir einige grundlegende und bew\u00e4hrte Prinzipien zeigen, welche dir durch hilfreiche Tricks und Tipps einen klareren Weg im Dschungel der vielen Ern\u00e4hrungsmythen aufzeigen sollen. Schlie\u00dflich kann die Person, die Prinzipien versteht, erfolgreich [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[58,61,46],"class_list":["post-3340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit-und-ernahrung","tag-ernaehrung","tag-ernaehrungsform","tag-personal-training"],"_links":{"self":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/3340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/comments?post=3340"}],"version-history":[{"count":0,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/3340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media\/3344"}],"wp:attachment":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media?parent=3340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/categories?post=3340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/tags?post=3340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}