{"id":3512,"date":"2021-11-08T10:17:22","date_gmt":"2021-11-08T09:17:22","guid":{"rendered":"https:\/\/mainperformance.de\/?p=3512"},"modified":"2021-11-08T10:40:28","modified_gmt":"2021-11-08T09:40:28","slug":"5-tipps-fuer-ein-unverwuestliches-immunsystem","status":"publish","type":"post","link":"https:\/\/mainperformance.de\/en\/5-tipps-fuer-ein-unverwuestliches-immunsystem\/","title":{"rendered":"5 Tipps, f\u00fcr ein unverw\u00fcstliches Immunsystem"},"content":{"rendered":"<p>Erst hatte es unser Immunsystem monatelang mit der COVID-19-Pandemie zu tun und nun scheinen sehr viele von einer Erk\u00e4ltung und Grippe betroffen zu sein.<\/p>\n<p>Vielleicht merkst du auch schon, dass du langsam wieder mehr auf dich achten musst, weil alle um dich herum anfangen zu kr\u00e4nkeln.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Aber warum treten Grippewellen gerade zu dieser Jahreszeit am meisten auf?<\/strong><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Die Viren, die eine klassische Influenza ausl\u00f6sen, k\u00f6nnen bei kalter und trockener Luft besser \u00fcberleben. Zudem halten wir uns bei k\u00e4lteren Temperaturen h\u00e4ufiger in Geb\u00e4uden mit anderen Menschen auf als an der frischen Luft, wo das Ansteckungsrisiko weitaus geringer w\u00e4re.<\/p>\n<p>Aktuell tragen wir zwar nahezu \u00fcberall Masken, wenn wir unter Menschen in R\u00e4umen unterwegs sind, allerdings erlauben uns die Lockerungen doch wieder mehr Kontakt zu anderen, was unser K\u00f6rper w\u00e4hrend des Lockdowns nicht gew\u00f6hnt war.<\/p>\n<p>Um das Risiko, an einer Grippe zu erkranken, zu verringern, solltest du ein gesundes Immunsystem haben.<\/p>\n<p>Hier sind ein paar Tipps aufgelistet, um ein unverw\u00fcstliches Immunsystem aufzubauen:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>1. Schlafe ausreichend und vermeide Stress<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Schlaf ist kein Luxus, sondern eine Notwendigkeit. Unz\u00e4hlige Studien haben gezeigt, dass Schlafmangel eine Vielzahl negativer hormoneller Probleme verursacht und zuletzt ein stark geschw\u00e4chtes Immunsystem hervorruft. Du bist am meisten ersch\u00f6pft und anf\u00e4llig f\u00fcr Erk\u00e4ltungen, wenn du zu wenig geschlafen hast und der K\u00f6rper nicht richtig regenerieren konnte.<\/p>\n<p>Auch zu viel Stress f\u00fchrt dazu, dass der K\u00f6rper dauerhaft unter Spannung steht und weniger Abwehrkr\u00e4fte aufbauen kann. Achte daher darauf, dass du dir im Alltag gen\u00fcgend Ruhephasen g\u00f6nnst. Oftmals ist es schwer, unter den vielen w\u00f6chentlichen Terminen Ruhe zu finden und manchmal kommen auch unvermeidbare Dinge dazwischen. Ein wenig vorbeugen kannst du aber, wenn du deine Woche genau im Voraus planst und deine Ruhe- und Freizeitphasen fest bestimmst.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>2. Trinke genug<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Der Rachen, genauer gesagt die Mandeln, sind die erste Barriere, die vor Viren sch\u00fctzen sollen und f\u00fcr ein gesundes Immunsystem arbeiten. Stelle sicher, dass du viel Wasser trinkst, da ein trockener Hals dazu f\u00fchren kann, dass in der Luft \u00fcbertragene Krankheitserreger schneller in den K\u00f6rper gelangen.<\/p>\n<p>Au\u00dferdem zerlegt Wasser die einzelnen Bestandteile aus der Nahrung und unterst\u00fctzt unsere Zellen bei der Aufnahme und Verteilung von Vitaminen, Enzymen, Mineralien und Spurenelementen im K\u00f6rper.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. Verwende die richtigen Supplements<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Wir empfehlen insbesondere diese zwei Supplements f\u00fcr ein starkes Immunsystem:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>YPSI MultiMineralComplex mit Zink<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Alle Mikron\u00e4hrstoffe, Vitamine und Mineralstoffe \u00fcbernehmen Aufgaben auf zellul\u00e4rer<\/p>\n<p>Ebene. Mikron\u00e4hrstoffe haben einen Einfluss auf die Energieproduktion, die Erholung, den Schlaf und die entz\u00fcndungshemmenden Prozesse im K\u00f6rper. Daher ist es wichtig, Mikron\u00e4hrstoffe in Form vom MultiKomplex zu sich zu nehmen, um das Immunsystem optimal zu st\u00e4rken.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Vitamin D<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Neben Vitamin C tr\u00e4gt auch Vitamin D zu einem gesunden Immunsystem bei. Die meisten untersch\u00e4tzen, dass das Sonnenlicht alleine nicht ausreicht, um einen optimalen Vitamin-D-Spiegel zu generieren. Im Winter empfiehlt es sich erst recht, Vitamin D zus\u00e4tzlich zu supplementieren.<\/p>\n<p>&nbsp;<\/p>\n<p>Um deinen Vitamin D Bedarf herauszufinden, lohnt es sich, einen zertifizierten Vitamin D Test zu machen. Wir empfehlen \u201eCerascreen\u201c. Den Teststreifen kannst du auf Amazon erwerben und anschlie\u00dfend die Blutprobenentnahme zuhause selbst machen. Danach kannst du den Teststreifen einfach ins Labor per Post einschicken. In wenigen Tagen bekommst du schon dein Testergebnis.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. Ern\u00e4hre dich gesund und ausgewogen<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Esse vorwiegend unverarbeitete, frische Lebensmittel<\/li>\n<li>Achte auf deine t\u00e4gliche Zufuhr an Makro-und Mikron\u00e4hrstoffen. Um dies zu kontrollieren, verwende Apps wie MyFitnessPal zum Kalorientracken<\/li>\n<li>Ersetze schlechte Kohlenhydrate wie Wei\u00dfbrot und Nudeln durch vollwertige Kohlenhydrate wie Vollkornnudeln, Reis, Quinoa und S\u00fc\u00dfkartoffeln<\/li>\n<li>Esse ausreichend Gem\u00fcse und 1-2 Sorten Obst pro Tag<\/li>\n<li>Achte zus\u00e4tzlich auf eine ausreichende Proteinzufuhr. 2-3 Gramm Protein pro Kilogramm K\u00f6rpergewicht sollten das Minimum sein.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>5. Bewege dich ausreichend <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Regelm\u00e4\u00dfiges moderates <a href=\"https:\/\/mainperformance.de\/en\/personal-training\/\">Training<\/a> und Bewegung sollen besonders vorteilhaft f\u00fcr die St\u00e4rkung des Immunsystems und die Verringerung des Infektionsrisikos sein. Besonders Ausdauersport im Freien unterst\u00fctzt die Immunfunktion des K\u00f6rpers. Aber auch nur, wenn du die richtige Funktionskleidung angepasst an die Temperaturen tr\u00e4gst!<\/p>\n<p>Hier eignet sich der \u201eZwiebellook\u201c. Zieh dich anfangs lieber etwas w\u00e4rmer in mehreren Schichten an an, sodass du gegebenenfalls eine Jacke ausziehen kannst.<\/p>\n<p>Durch Sport produziert der K\u00f6rper mehr Abwehrzellen gegen Viren und Bakterien. Allerdings sollte man es hier auch nicht \u00fcbertreiben und dem K\u00f6rper gen\u00fcgend Ruhephasen zwischen den Trainingseinheiten g\u00f6nnen. Bist du schon geschw\u00e4cht, solltest du es unbedingt langsam angehen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fazit<\/strong><\/p>\n<p>Gerade zu dieser Jahreszeit ist es enorm wichtig, dass du auf dich Acht gibst und ein paar Dinge f\u00fcr dich und deinen K\u00f6rper tust, die dein Immunsystem st\u00e4rken und sch\u00fctzen. Durch Befolgung der einfachen Regeln wirst du dich garantiert besser f\u00fchlen und sagst automatisch den Viren den Kampf an.<\/p>\n<p>Wenn es dich doch mal erwischen sollte, ignoriere dies auf keinen Fall. Eine verschleppte Erk\u00e4ltung, die du nicht richtig auskurierst, kann sich sehr lange ziehen. H\u00f6re deshalb auf die Signale deines K\u00f6rpers, ruh dich rechtzeitig aus und bleibe zuhause, sodass du schnell regenerieren kannst.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quellenangaben<\/strong><\/p>\n<ul>\n<li>RKI (2021). Warum treten Grippewellen immer im Winter auf? Abgerufen am 01.11.2021. Online verf\u00fcgbar unter: <a href=\"https:\/\/www.rki.de\/SharedDocs\/FAQ\/Influenza\/FAQ02.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.rki.de\/SharedDocs\/FAQ\/Influenza\/FAQ02.html<\/a><\/li>\n<li>Stern (2007). St\u00e4rkt Sport das Immunsystem? Abgerufen am 01.11.2021. Online verf\u00fcgbar unter: https:\/\/www.stern.de\/gesundheit\/das-juengste-geruecht-staerkt-sport-das-immunsystem&#8211;3262532.html<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Erst hatte es unser Immunsystem monatelang mit der COVID-19-Pandemie zu tun und nun scheinen sehr viele von einer Erk\u00e4ltung und Grippe betroffen zu sein. Vielleicht merkst du auch schon, dass du langsam wieder mehr auf dich achten musst, weil alle um dich herum anfangen zu kr\u00e4nkeln. &nbsp; Aber warum treten Grippewellen gerade zu dieser Jahreszeit [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,26],"tags":[58,59,66,46],"class_list":["post-3512","post","type-post","status-publish","format-standard","hentry","category-gesundheit-und-ernahrung","category-lifestyle","tag-ernaehrung","tag-gesundheit","tag-immunsystem","tag-personal-training"],"_links":{"self":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/3512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/comments?post=3512"}],"version-history":[{"count":0,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/3512\/revisions"}],"wp:attachment":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media?parent=3512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/categories?post=3512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/tags?post=3512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}