{"id":3854,"date":"2022-02-17T08:22:21","date_gmt":"2022-02-17T07:22:21","guid":{"rendered":"https:\/\/mainperformance.de\/?p=3854"},"modified":"2022-02-17T11:03:29","modified_gmt":"2022-02-17T10:03:29","slug":"koerpertypen","status":"publish","type":"post","link":"https:\/\/mainperformance.de\/en\/koerpertypen\/","title":{"rendered":"K\u00f6rpertypen &#8211; Sind wir alle aus dem gleichen Holz geschnitzt?"},"content":{"rendered":"<p>Du wirst uns sicher zustimmen, dass es unterschiedliche K\u00f6rpertypen gibt, oder?<\/p>\n<p>&nbsp;<\/p>\n<p>Einige sind genetisch schlank und haben M\u00fche, Muskeln aufzubauen und kein K\u00f6rperfett zuzulegen, andere brauchen nur das kleinste bisschen schlechtes Essen anzuschauen und schon nehmen sie K\u00f6rperfett zu.<\/p>\n<p>Eines der Probleme, die wir sehen, ist, dass zu viele Menschen die Ern\u00e4hrung anderer kopieren, ohne auf ihre eigene genetische Veranlagung zu achten. Sie fragen sich, warum sie mit einer kohlenhydratreichen Ern\u00e4hrung Fett zunehmen, und andere fragen sich, warum sie mit einer einfachen Paleo-Ern\u00e4hrung (\u00fcberwiegend mageres Fleisch oder Fisch, Gem\u00fcse, Obst und essenzielle Fette) nicht an Masse gewinnen k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Im Leben neigen die Menschen auch dazu, sich je nach ihrer genetischen Veranlagung bestimmten Sportarten zuzuwenden. Schlankere M\u00e4nner und Frauen tendieren eher zu Langstreckenl\u00e4ufen, w\u00e4hrend st\u00e4mmigere und muskul\u00f6sere M\u00e4nner\/Frauen eher Kraftsportarten wie Sprinten betreiben.<\/p>\n<p>&nbsp;<\/p>\n<p>Es gibt zwar eine bestimmte Art und Weise, wie wir die Menschen bei Mainperformance trainieren, um gesund zu sein, aber f\u00fcr die K\u00f6rperzusammensetzung und die Leistung gehen wir ein bisschen tiefer. Wie in unserem Artikel \u00fcber <a href=\"https:\/\/mainperformance.de\/en\/carb-cycling\/\">Carb-Cycling<\/a>\u00a0gibt es verschiedene Ans\u00e4tze f\u00fcr Ern\u00e4hrungsstrategien, und du musst den f\u00fcr dich richtigen w\u00e4hlen.<\/p>\n<p>An dieser Stelle kommt das Verst\u00e4ndnis der verschiedenen K\u00f6rpertypen ins Spiel. Nimm dir einen Moment Zeit und sie dir das folgende Bild an. Du wirst dich sofort mit einem der unterschiedlichen K\u00f6rpertypen identifizieren k\u00f6nnen, egal ob du ein Mann oder eine Frau bist.<\/p>\n<p>&nbsp;<\/p>\n<p>Es erstaunt uns immer wieder, wenn Menschen zu einem Beratungsgespr\u00e4ch kommen und uns sofort sagen, dass sie ihren K\u00f6rpertyp kennen und wissen, warum sie kein K\u00f6rperfett verlieren k\u00f6nnen. Sie sind einfach so geboren!<\/p>\n<p>&nbsp;<\/p>\n<p>Stell dir diese Frage: Wurdest du fett oder \u00fcbergewichtig geboren? Wir glauben nicht!<\/p>\n<p>&nbsp;<\/p>\n<p>In vielen F\u00e4llen hast du im Laufe der Zeit zu viel gegessen, dich zu wenig bewegt, deine Hormone durch Lebensstilprobleme, wie Schlafmangel und Stress, durcheinandergebracht und deine lebenswichtigen Organe, die f\u00fcr wichtige Funktionen wie die Entgiftung deines K\u00f6rpers zust\u00e4ndig sind, \u00fcberlastest.<\/p>\n<p>Die gute Nachricht ist, dass diese Probleme behoben werden k\u00f6nnen, und du am Ende dieses Artikels mehr \u00fcber diese Themen lesen kannst.<\/p>\n<p>&nbsp;<\/p>\n<p>In fast allen F\u00e4llen wollen alle M\u00e4nner und Frauen, die zu uns kommen, schlanker und st\u00e4rker werden sowie etwas Muskelmasse aufbauen (beides ist f\u00fcr den Fettabbau unerl\u00e4sslich). Das kann aus reiner Eitelkeit geschehen oder um die sportliche Leistung zu verbessern, wenn du ein Sportler bist.<\/p>\n<p>&nbsp;<\/p>\n<p>In vielen Ver\u00f6ffentlichungen ist zu lesen, dass M\u00e4nner und Frauen genetisch bedingt &#8222;dicker gebaut&#8220; sein k\u00f6nnen und dass sie eher als die meisten Menschen dazu neigen, \u00fcbersch\u00fcssiges K\u00f6rperfett zu speichern.<\/p>\n<p>&nbsp;<\/p>\n<p>Aus unserer eigenen Erfahrung mit der Messung des K\u00f6rperfetts vieler Kunden k\u00f6nnen wir best\u00e4tigen, dass dies stimmt, aber das bedeutet nicht, dass du dich einfach zur\u00fccklehnen und nachgeben solltest, sondern dass du deine Ern\u00e4hrung und dein Training entsprechend auf deine Figur abstimmen musst.<\/p>\n<p>Bei <a href=\"https:\/\/mainperformance.de\/en\/personal-training\/\">Mainperformance<\/a> gilt ein Mann mit einem K\u00f6rperfettanteil von etwa 10 % und eine Frau mit einem K\u00f6rperfettanteil von etwa 14 % als schlank. Alles dar\u00fcber kann als \u00fcberfl\u00fcssiges und unn\u00f6tiges K\u00f6rperfett kategorisiert werden.<\/p>\n<p>&nbsp;<\/p>\n<p>Wenn wir ein Ern\u00e4hrungsprogramm f\u00fcr unsere Kunden schreiben, dann orientieren wir uns an der K\u00f6rperform desjenigen und nicht daran, was er f\u00fcr einen genetischen K\u00f6rpertyp h\u00e4lt. Das gibt uns einen guten Anhaltspunkt, um das Verh\u00e4ltnis der Makron\u00e4hrstoffe (Kohlenhydrate, Proteine und Fette) zu bestimmen, welche die Kunden ben\u00f6tigen.<\/p>\n<p>&nbsp;<\/p>\n<p>Vor diesem Hintergrund behandeln wir die einzelnen K\u00f6rpertypen folgenderma\u00dfen, wenn sie zu uns kommen (siehe die Bilder oben, um die K\u00f6rpertypen zuzuordnen):<\/p>\n<p>&nbsp;<\/p>\n<p><strong>EKTOMORPH<\/strong><\/p>\n<ul>\n<li>Ziel =&gt; Muskelmasse aufbauen &amp; K\u00f6rperfettreduktion<\/li>\n<li>typischerweise sehr schmaler Knochenbau (d\u00fcnne Hand- und Fu\u00dfgelenke)<\/li>\n<li>Schwierigkeiten Muskelmasse aufzubauen \u2013 gleichzeitig kein Problem mit \u00fcbersch\u00fcssigem K\u00f6rperfett<\/li>\n<li>ausreichende Kalorienzufuhr hat Vorrang<\/li>\n<li>Gesamtmenge der Nahrung Grund warum keine Masse aufgebaut wird<\/li>\n<li>Gute Kohlenhydrat-Toleranz =&gt; Daher zu jeder Mahlzeit hinzuf\u00fcgen<\/li>\n<li>Post-Workout-Shake zuckerhaltige Kohlenhydrate hinzuf\u00fcgen<\/li>\n<li>Eiwei\u00df Gem\u00fcse und eine mittlere Portion essenzieller Fette (wie Avocado, N\u00fcsse und Samen) zu jeder Mahlzeit wichtig<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>MESOMORPH<\/strong><\/p>\n<ul>\n<li>Ziel =&gt; K\u00f6rperfettreduktion &amp; Muskelaufbau<\/li>\n<li>tendenziell muskul\u00f6ser &amp; dickere Knochenstruktur (m\u00e4nnlich oder weiblich)<\/li>\n<li>schnell Gewichtszuanhme<\/li>\n<li>WICHTIG =&gt; N\u00e4hrstoffe zeitlich angemessen dosieren<\/li>\n<li>durchschnittliche Toleranz gegen\u00fcber Kohlenhydraten =&gt; auf eine Mahlzeit pro Tag beschr\u00e4nken<\/li>\n<li>Post-Workout-Shake zuckerhaltige Kohlenhydrate hinzuf\u00fcgen<\/li>\n<li>Hauptmahlzeiten =&gt; ausreichende Mengen mageres Eiwei\u00df, mittlere Mengen essenzielle Fette und gro\u00dfe Mengen Gem\u00fcse<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>ENDOMORPH<\/strong><\/p>\n<ul>\n<li>Ziel =&gt; viel K\u00f6rperfett zu verlieren<\/li>\n<li>K\u00f6rpertyp das Ergebnis einer Ern\u00e4hrung st\u00e4rkehaltige Kohlenhydraten wie Pizza, Nudeln und Brot<\/li>\n<li>vertragen keine zuckerhaltigen Lebensmittel<\/li>\n<li>nehmen leicht K\u00f6rperfett zu<\/li>\n<li>St\u00e4rkehaltige Kohlenhydrate komplett aus der Ern\u00e4hrung streichen bis Zielgewicht erreicht<\/li>\n<li>Schwerpunkt der Ern\u00e4hrung liegt auf magerem Fleisch, Fisch, essenziellen Fetten und viel Gem\u00fcse<\/li>\n<li>regelm\u00e4\u00dfig \u00fcber den Tag verteilt kleinere Portionen essen, um Hungerl\u00f6cher zu vermeiden<\/li>\n<li>Training sollte einen gro\u00dfen Teil der Woche ausmachen (&gt;3 Einheiten\/ Woche)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Wenn du nach dem Lesen dieses Artikels feststellst, dass du dich entsprechend deiner K\u00f6rperform anders ern\u00e4hrst, wende einige unserer Tipps an und lass uns wissen, wie du damit zurechtkommst.<\/p>\n<p>Zu viele Menschen geben den Genen die Schuld daran, dass sie nicht abnehmen k\u00f6nnen oder Schwierigkeiten haben, Muskelmasse aufzubauen.<\/p>\n<p>Doch aus Erfahrung wissen wir, dass es oft an mangelnder Disziplin bei der Ern\u00e4hrung liegt und an der Unf\u00e4higkeit, hart genug zu trainieren, um die gew\u00fcnschten Ergebnisse zu erzielen.<\/p>\n<p><strong>Quelle: <\/strong><\/p>\n<p>M10 \u2013 Marc Coles, M\u00e4rz 2018<\/p>","protected":false},"excerpt":{"rendered":"<p>Du wirst uns sicher zustimmen, dass es unterschiedliche K\u00f6rpertypen gibt, oder? &nbsp; Einige sind genetisch schlank und haben M\u00fche, Muskeln aufzubauen und kein K\u00f6rperfett zuzulegen, andere brauchen nur das kleinste bisschen schlechtes Essen anzuschauen und schon nehmen sie K\u00f6rperfett zu. Eines der Probleme, die wir sehen, ist, dass zu viele Menschen die Ern\u00e4hrung anderer kopieren, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,30],"tags":[],"class_list":["post-3854","post","type-post","status-publish","format-standard","hentry","category-gesundheit-und-ernahrung","category-gewichtsreduktion"],"_links":{"self":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/3854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/comments?post=3854"}],"version-history":[{"count":0,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/3854\/revisions"}],"wp:attachment":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media?parent=3854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/categories?post=3854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/tags?post=3854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}