{"id":4876,"date":"2022-08-03T15:45:33","date_gmt":"2022-08-03T13:45:33","guid":{"rendered":"https:\/\/mainperformance.de\/?p=4876"},"modified":"2022-08-03T15:52:36","modified_gmt":"2022-08-03T13:52:36","slug":"10-gruende-fuer-krafttraining","status":"publish","type":"post","link":"https:\/\/mainperformance.de\/en\/10-gruende-fuer-krafttraining\/","title":{"rendered":"10 erstaunliche Gr\u00fcnde, warum Du Krafttraining machen solltest"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4876\" class=\"elementor elementor-4876\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98fc983 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98fc983\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87825ca\" data-id=\"87825ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88f7372 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"88f7372\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;no_headings_message&quot;:&quot;No headings were found on this page.&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tInhaltsverzeichnis\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__88f7372\" aria-expanded=\"true\" aria-label=\"Open table of contents\"><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__88f7372\" aria-expanded=\"true\" aria-label=\"Close table of contents\"><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__88f7372\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-799da3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"799da3f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78b1fdf\" data-id=\"78b1fdf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0adf741 elementor-widget elementor-widget-text-editor\" data-id=\"0adf741\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jeder sollte Krafttraining machen. Es gibt keine andere Trainingsart, die dir so viele erstaunliche k\u00f6rperliche, geistige und allgemeine gesundheitliche Vorteile bringt, wie das Krafttraining.<\/p><p>Wenn du Gewichte hebst, lernst du, wozu du f\u00e4hig bist. Deinen K\u00f6rper zu fordern ist eine au\u00dfergew\u00f6hnliche Methode, um die St\u00e4rke deines Geistes zu entwickeln.<\/p><p>Wenn du die Tiefe deines Antriebs entdeckst, lernst du, durchzuhalten und Misserfolge zu \u00fcberwinden &#8211; wir alle haben harte Tage im Fitnessstudio, aber das sind die, die den Unterschied ausmachen.<\/p><p>Wenn du schwere Lasten hebst, wirst du dein Leben zum Besseren wenden und Selbstvertrauen entwickeln. K\u00f6rperliche St\u00e4rke gibt dir ein beruhigendes Gef\u00fchl f\u00fcr deinen Platz in der Welt: Das Wissen, dass Klimmz\u00fcge m\u00fchelos m\u00f6glich sind oder dass du mehr als dein K\u00f6rpergewicht in die Hocke bringen kannst, hat eine bemerkenswert positive Wirkung auf dein Selbstwertgef\u00fchl.<\/p><p>Das Wichtigste ist, dass du eine Sportart w\u00e4hlst, die dir Spa\u00df macht &#8211; damit du dabei bleibst.<\/p><p>Diese 10 erstaunlichen Vorteile sollen dir das Krafttraining nahe bringen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e888893 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e888893\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae05429\" data-id=\"ae05429\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af43c7d elementor-widget elementor-widget-heading\" data-id=\"af43c7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gewichte verbessern deine K\u00f6rperzusammensetzung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34a56c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34a56c6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3929cf\" data-id=\"e3929cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa8f88c elementor-widget elementor-widget-text-editor\" data-id=\"fa8f88c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der beste Weg zu einem schlanken K\u00f6rperbau ist die Kombination von Ern\u00e4hrung und Krafttraining. Ganz gleich, ob du &#8222;schlank&#8220;, &#8222;dick&#8220; oder &#8222;straff&#8220; werden willst, mit Gewichtstraining und einer gesunden Ern\u00e4hrung l\u00e4sst sich dieses Ziel am einfachsten erreichen.<\/p><p>So zeigte eine Studie, dass 28 untrainierte, leicht \u00fcbergewichtige M\u00e4nner, die 8 Wochen lang dreimal pro Woche ein Hypertrophieprogramm absolvierten, 3 kg K\u00f6rperfett verloren, was einer Abnahme des K\u00f6rperfettanteils um 13 Prozent entsprach. Au\u00dferdem nahmen sie im Vergleich zu einer Kontrollgruppe, bei der sich die K\u00f6rperzusammensetzung nicht ver\u00e4nderte, 3 kg an fettfreier Muskulatur zu.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-832aed1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"832aed1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f58c7f6\" data-id=\"f58c7f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa4257 elementor-widget elementor-widget-heading\" data-id=\"caa4257\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Krafttraining hilft beim Fettabbau\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e13fdb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e13fdb1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd769c2\" data-id=\"cd769c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f03170c elementor-widget elementor-widget-text-editor\" data-id=\"f03170c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die g\u00e4ngige Meinung, dass aerobes Training die L\u00f6sung f\u00fcr <a href=\"http:\/\/Fett\" data-wplink-url-error=\"true\">Fettleibigkeit<\/a> ist, verkennt den \u00fcberw\u00e4ltigenden Nutzen des Muskelaufbaus. Mehr Muskeln sind gleichbedeutend mit mehr Kalorien, die im Ruhezustand verbrannt werden. So zeigt eine umfangreiche Auswertung ver\u00f6ffentlichter Forschungsergebnisse, dass Krafttraining sowohl bei normal- als auch bei \u00fcbergewichtigen Personen zu einem durchschnittlichen Verlust von 1,7 kg Fett f\u00fchrt, w\u00e4hrend die fettfreie Masse und die Stoffwechselrate erhalten bleiben.<\/p><p>In einer Studie, die diesen Effekt weiter ausf\u00fchrt, wurde untersucht, was passiert, wenn man eine Di\u00e4t macht und Gewichte hebt: Zwanzig untrainierte \u00fcbergewichtige Frauen, die 12 Wochen lang ein Zirkeltraining im Hypertrophie-Stil absolvierten, verloren 14,5 kg K\u00f6rperfett. Sie steigerten die Kalorienmenge, die ihr K\u00f6rper in Ruhe verbrannte, um 63 Kalorien, so dass sie einen Ruheumsatz (RMR) von 1.800 hatten. Die Studie zeigte auch, was passiert, wenn man sich bei einer kalorienreduzierten Di\u00e4t f\u00fcr aerobes Training entscheidet: Diese Frauen verloren 12,8 kg K\u00f6rperfett und bauten 4 kg Muskeln ab, was leider ihren RMR um 210 Kalorien auf mickrige 1.358 pro Tag reduzierte! Ja, das ist richtig, die aerobe Arbeit verschlechterte ihren Ruheumsatz!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3840400 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3840400\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-561c4cb\" data-id=\"561c4cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4ba539 elementor-widget elementor-widget-heading\" data-id=\"f4ba539\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Training baut bevorzugt schnell Muskeln auf, die den Stoffwechsel erh\u00f6hen\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f351fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f351fa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0bdd41c\" data-id=\"0bdd41c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cee72d8 elementor-widget elementor-widget-text-editor\" data-id=\"cee72d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jeder wei\u00df, wie der Muskelaufbau zum Abnehmen sorgt: Erstens gibt es den <a href=\"https:\/\/mainperformance.de\/super-fat-loss-workouts\/\">Nachbrenneffekt<\/a> des Trainings, der bis zu 38 Stunden nach dem Training anh\u00e4lt. Zweitens: Je mehr Muskeln du hast, desto mehr kannst du essen, da die Stoffwechselkosten f\u00fcr den Erhalt dieser Muskeln h\u00f6her sind. Drittens werden beim Sport fettverbrennende und muskelaufbauende Hormone ausgesch\u00fcttet, die dir helfen, schlank und rank zu werden (und zu bleiben).<\/p><p>Du wusstest wahrscheinlich nicht, dass der Stoffwechselvorteil, den du durch Krafttraining erzielst, noch spezifischer ist: Das Heben schwerer Lasten in kurzen St\u00f6\u00dfen beg\u00fcnstigt den Aufbau der kraftvollsten Muskelfasern vom Typ II, die die h\u00f6chsten Stoffwechselkosten haben. Der Aufbau der schnell zuckenden Muskeln steigert den Stoffwechsel exponentiell mehr, als wenn du die gleiche Menge an Arbeit mit geringer Kraft verrichtest, wie es f\u00fcr aerobes Ausdauertraining typisch ist.<\/p><p>Denke daran, dass aufgrund des Gr\u00f6\u00dfenprinzips bei der Rekrutierung von Muskelfasern das Training der leistungsst\u00e4rksten Typ-II-Fasern ein kaskadenartiges Training aller schw\u00e4cheren Fasern erfordert, was ein Training mit schweren Lasten umso vorteilhafter macht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8ba243 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8ba243\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-396e955\" data-id=\"396e955\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fa20ea elementor-widget elementor-widget-heading\" data-id=\"6fa20ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gewichte verbessern das Nervensystem und die Genverl\u00e4ufe\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb83fc2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb83fc2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c4dcef\" data-id=\"8c4dcef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb750f5 elementor-widget elementor-widget-text-editor\" data-id=\"fb750f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Krafttrainer wissen seit Jahrzehnten, dass das Heben von Gewichten das zentrale Nervensystem trainiert, so dass sie schneller reagieren, einen schnelleren ersten Schritt machen und in der Lage sind, mehr Kraft auf den Boden zu \u00fcbertragen. Wenn du deine neuromuskul\u00e4re Kraft aufbaust, arbeitet dein K\u00f6rper effizienter.<\/p><p>Ein starkes neuromuskul\u00e4res System wirkt sich auf alle Altersgruppen aus und ist ein wichtiger Indikator f\u00fcr Langlebigkeit und Wohlbefinden. Dar\u00fcber hinaus gibt es neue Erkenntnisse dar\u00fcber, wie Gewichtheben die genetischen Bahnen hochreguliert, die das Altern verhindern, besch\u00e4digtes Gewebe wieder aufbauen, Energie verbrennen und Sauerstoff nutzen. Dies f\u00fchrt zu einer besseren Gehirnfunktion und Bewegungskoordination bei Jung und Alt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd49896 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd49896\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7561946\" data-id=\"7561946\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76fcb32 elementor-widget elementor-widget-heading\" data-id=\"76fcb32\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Krafttraining erh\u00f6ht die Ausdauer von Amateur- und Profisportlern\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-796db79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"796db79\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40a8fff\" data-id=\"40a8fff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd4bac0 elementor-widget elementor-widget-text-editor\" data-id=\"bd4bac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Es wurde wiederholt nachgewiesen, dass Krafttraining den K\u00f6rperfettanteil bei Ausdauersportlern wie Radfahrern und Langstreckenl\u00e4ufern senkt (in einer d\u00e4nischen Studie verloren die Radrennfahrer der Nationalmannschaft nach 16 Wochen Training 2 Prozent K\u00f6rperfett), und jeder wei\u00df, dass ein leichterer Athlet ein besserer Athlet ist, wenn es um den K\u00f6rperfettanteil geht.<\/span><\/p><p>Dies f\u00fchrt zu einer Steigerung der maximalen Kapazit\u00e4t des K\u00f6rpers f\u00fcr den Sauerstofftransport sowie zu einer verst\u00e4rkten adaptiven Signalgebung in den Muskeln f\u00fcr eine h\u00f6here Arbeitskapazit\u00e4t und Geschwindigkeit (die d\u00e4nischen Radfahrer absolvierten ein 5-Minuten-Zeitfahren um 5 % und ein 45-Minuten-Zeitfahren um 8 % schneller als eine Kontrollgruppe).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0112dc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0112dc6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f548f10\" data-id=\"f548f10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19531fa elementor-widget elementor-widget-heading\" data-id=\"19531fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Krafttraining senkt den Blutdruck und verbessert die Herzfunktion\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c362be0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c362be0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfbb209\" data-id=\"bfbb209\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-109ad36 elementor-widget elementor-widget-text-editor\" data-id=\"109ad36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Krafttraining verbessert die Herzfunktion dramatisch. Es hat sich wiederholt gezeigt, dass es den <a href=\"https:\/\/mainperformance.de\/fakten-ueber-deinen-blutdruck\/\">Blutdruck<\/a> senkt &#8211; eine \u00dcberpr\u00fcfung ergab, dass in 8 Studien der systolische Blutdruck (SBP) um durchschnittlich 6,2 mmHg gesenkt wurde. Dies ist klinisch bedeutsam, da der Nutzen mehr als doppelt so gro\u00df ist wie bei den \u00fcblichen blutdrucksenkenden Medikamenten.<\/p><p>Krafttraining verbessert auch die Arterienfunktion und verringert Entz\u00fcndungen &#8211; eine Untersuchung zeigte, dass \u00e4ltere Frauen, die mit ihrem Gewicht trainierten, weniger C-reaktives Protein aufwiesen, einen Marker f\u00fcr oxidativen Stress, der einen Entz\u00fcndungszustand verursacht. Die kombinierte Wirkung von niedrigerem Blutdruck, weniger Entz\u00fcndungen und besserem Blutfluss verringert das Risiko f\u00fcr Herz-Kreislauf-Erkrankungen um mehr als 14 Prozent.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de71d3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de71d3f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6291f0\" data-id=\"c6291f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71ff0ef elementor-widget elementor-widget-heading\" data-id=\"71ff0ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Krafttraining verbessert den Schlaf und verringert chronische Schmerzen\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f21643 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f21643\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb5a5e2\" data-id=\"cb5a5e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e42df50 elementor-widget elementor-widget-text-editor\" data-id=\"e42df50\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine k\u00fcrzlich durchgef\u00fchrte Interventionsstudie zeigte, dass sich bei gesunden \u00e4lteren M\u00e4nnern, die ein Hypertrophieprogramm absolvierten, die <a href=\"http:\/\/Schlafqu\" data-wplink-url-error=\"true\">Schlafqualit\u00e4t<\/a> um 5 Prozent verbesserte und sie nachts weniger oft aufwachten. Die Forscher vermuten, dass die langfristigen Auswirkungen eines besseren Schlafs tiefgreifend sind, da er die Kontrolle des Blutzuckerspiegels, das Diabetesrisiko, die Zunahme des K\u00f6rperfetts und den Entz\u00fcndungsstatus beeinflusst.<\/p><p>Interessant ist eine Reihe von Studien, die zeigen, dass Krafttraining bei \u00e4lteren Menschen \u00fcber 50 Jahren die Schmerzwahrnehmung um 43 % verringern kann, indem es Anpassungen bewirkt, die die Schmerzschwelle erh\u00f6hen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-756f9bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"756f9bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8981ba3\" data-id=\"8981ba3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b17b21e elementor-widget elementor-widget-heading\" data-id=\"b17b21e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Krafttraining beugt Krankheiten vor, insbesondere Krebs und Diabetes\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2063ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2063ea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6019517\" data-id=\"6019517\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b8b113 elementor-widget elementor-widget-text-editor\" data-id=\"6b8b113\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">\u00c4rzte, die sich auf die Behandlung von <a href=\"https:\/\/mainperformance.de\/krafttraining-diabetes\/\">Diabetes<\/a> spezialisiert haben, setzen auf Ern\u00e4hrung und Bewegung. Berichte aus der Praxis zeigen, dass Krafttraining und andere anaerobe Trainingsformen wie moderates Intervalltraining am effektivsten sind. Krafttraining hat einen dramatischen Einfluss auf die Blutzuckerfunktion und die Insulingesundheit. Der Aufbau von Muskeln erh\u00f6ht die Empf\u00e4nglichkeit des fettfreien Gewebes f\u00fcr Insulin und steigert den Bedarf der Muskeln an Glukose, wodurch diese aus dem Blutkreislauf herausgezogen wird. Dies tr\u00e4gt zu einer besseren K\u00f6rperzusammensetzung und zur Diabetespr\u00e4vention bei.<\/span><\/p><p>Es hat sich auch wiederholt gezeigt, dass Krafttraining mit einem geringeren Risiko f\u00fcr eine Reihe von Krebsarten korreliert. So ist das Brustkrebsrisiko bei Teenager-M\u00e4dchen im sp\u00e4teren Leben am st\u00e4rksten reduziert. Der Nutzen f\u00fcr die Krebspr\u00e4vention erstreckt sich auf Frauen jeden Alters.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0026bbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0026bbb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-467a3a3\" data-id=\"467a3a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ada2e0e elementor-widget elementor-widget-heading\" data-id=\"ada2e0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Krafttraining verbessert den Hormonspiegel und die Fortpflanzungsfunktion\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d212a3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d212a3b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ff9c3a\" data-id=\"6ff9c3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b28b38e elementor-widget elementor-widget-text-editor\" data-id=\"b28b38e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Krafttraining hat eine viel st\u00e4rkere Wirkung auf die <a href=\"https:\/\/mainperformance.de\/10-fakten-ueber-den-hormonhaushalt\/\">Hormonfunktion<\/a> als nur der Anstieg des Testosteronspiegels, den M\u00e4nner nach dem Training erfahren. Der Aufbau schlanker Muskeln im Rahmen eines 12-w\u00f6chigen Trainingsprogramms verbesserte den \u00d6strogenstoffwechsel bei jungen Frauen, was bemerkenswert ist, da ein besserer \u00d6strogenabbau ein geringeres Krebsrisiko und weniger K\u00f6rperfett bedeutet.<\/span><\/p><p>Jeder wei\u00df, dass Training die Wachstumshormone und IGF-1 erh\u00f6ht, die beide mit Schlankheit in Verbindung stehen. Krafttraining f\u00fchrt auch zu einer besseren Regulierung der Hormone, die mit Hunger und Energieverbrauch zusammenh\u00e4ngen. Es bek\u00e4mpft den oxidativen Stress durch Cortisol und verwandte gewebeabbauende Hormone, die als Nebeneffekt auch die reproduktive Gesundheit sch\u00e4digen k\u00f6nnen, wenn sie dauerhaft erh\u00f6ht sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c488c73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c488c73\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-839e52e\" data-id=\"839e52e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-167d081 elementor-widget elementor-widget-heading\" data-id=\"167d081\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schwere Gewichte baut Knochen auf<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-166bc57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"166bc57\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d73c3cc\" data-id=\"d73c3cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c648dc0 elementor-widget elementor-widget-text-editor\" data-id=\"c648dc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Gewichtstraining ist mit Abstand die beste Aktivit\u00e4t zum Aufbau von Knochenmasse und -dichte. Studien zeigen, dass ehemalige Spitzensportler, die Gewichtheben in ihr Training einbezogen haben, im Alter viel st\u00e4rkere Knochen haben. Dies f\u00fchrt bei M\u00e4nnern zu einem um 50 Prozent und bei Frauen zu einem um 20 Prozent geringeren Frakturrisiko.<\/span><\/p><p>Um Knochen aufzubauen, solltest du regelm\u00e4\u00dfig im Hypertrophie- und Kraftbereich trainieren und dabei auch Zyklen einbauen, in denen du maximale Lasten hebst &#8211; das hei\u00dft, das h\u00f6chste Gewicht, das du f\u00fcr ein oder zwei Wiederholungen pro Satz stemmen kannst. Auch plyometrische \u00dcbungen und das Tragen einer Gewichtsweste sind ideal f\u00fcr den Knochenaufbau.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8ad454 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8ad454\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d29397\" data-id=\"0d29397\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0b89a0 elementor-widget elementor-widget-heading\" data-id=\"a0b89a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Referenzen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c92a0d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c92a0d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60e7535f\" data-id=\"60e7535f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-418fd444 elementor-widget elementor-widget-text-editor\" data-id=\"418fd444\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Schuenke, M., et al. Effect of an Acute Period of Resistance Exercise on Excess Post-Exercise Oxygen Consumption. European Journal of Applied Physiology. 2002. 86(5), 411-417.<\/span><\/p><p>Bryner, R., et al. Effects of Resistance Vs. Aerobic Training Combined with an 800 Calorie Liquid Diet on Lean Body Mass and Resting Metabolic Rate. Journal of the American College of Nutrition. 1999. 18(2), 115-121.<\/p><p>Shaw, I., et al. Consequence of Resistance Training on Body Composition and Coronary Artery Disease Risk. Cardiovascular Journal of South Africa. 2006. 17(3), 111-116.<\/p><p>Campbell, K., et al. Effects of Aerobic Exercise Training on Estrogen Metabolism in Premenopausal Women. Cancer Epidemiology, Biomarkers &amp; Prevention. 2007. 16, 731-739.<\/p><p>Moghadasi, M., et al. The Effect of 12 Weeks of Resistance Training on Hormones of Bone Formation in Young Sedentary women. European Journal Applied Physiology. 2012. Published Ahead of Print.<\/p><p>Ebben, W., et al. Magnitude and Rate of Mechanical Loading of a Variety of Exercise Modes. Journal of Strength and Conditioning Research. 2010. 24(1), 213-217.<\/p><p>Ebben, W., et al. The Optimal Back Squat Load for Potential Osteogenesis. Journal of Strength and Conditioning Research. 2010. 26(5), 1232-1237.<\/p><p>Aagaard, P., Andersen J., et al. Effects of Resistance Training on Endurance Capacity and Muscle Fiber Composition in Young Top-Level Cyclists. Scandinavian Journal of Medicine and Science in Sports. 2011. Published Ahead of Print.<\/p><p>Vaamonde, D., Silva-Grigoletto, M., et al. Physically Active Men Show Better Semen Parameters and Hormone Values than Sedentary Men. European Journal of Applied Physiology. 2012. Published Ahead of Print.<\/p><p>Wllingson, L., Colbert, L., et al. Physical Activity is Related to Pain Sensitivity in Healthy Women. Medicine and Science in Sports and Exercise. 2011. Published Ahead of Print.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Inhaltsverzeichnis Jeder sollte Krafttraining machen. Es gibt keine andere Trainingsart, die dir so viele erstaunliche k\u00f6rperliche, geistige und allgemeine gesundheitliche Vorteile bringt, wie das Krafttraining. Wenn du Gewichte hebst, lernst du, wozu du f\u00e4hig bist. Deinen K\u00f6rper zu fordern ist eine au\u00dfergew\u00f6hnliche Methode, um die St\u00e4rke deines Geistes zu entwickeln. Wenn du die Tiefe deines [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[45],"class_list":["post-4876","post","type-post","status-publish","format-standard","hentry","category-training","tag-krafttraining"],"_links":{"self":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/4876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/comments?post=4876"}],"version-history":[{"count":0,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/4876\/revisions"}],"wp:attachment":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media?parent=4876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/categories?post=4876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/tags?post=4876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}