{"id":4974,"date":"2022-09-02T06:55:33","date_gmt":"2022-09-02T04:55:33","guid":{"rendered":"https:\/\/mainperformance.de\/?p=4974"},"modified":"2022-09-01T16:21:00","modified_gmt":"2022-09-01T14:21:00","slug":"10-hartnaeckige-kniebeugen-mythen","status":"publish","type":"post","link":"https:\/\/mainperformance.de\/en\/10-hartnaeckige-kniebeugen-mythen\/","title":{"rendered":"10 extrem hartn\u00e4ckige Kniebeugen-Mythen, die nicht verschwinden werden"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4974\" class=\"elementor elementor-4974\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8da1025 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8da1025\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92c8989\" data-id=\"92c8989\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d9a6ea elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"4d9a6ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;no_headings_message&quot;:&quot;Es wurden keine \\u00dcberschriften auf dieser Seite gefunden.&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tInhaltsverzeichnis\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__4d9a6ea\" aria-expanded=\"true\" aria-label=\"Inhaltsverzeichnis \u00f6ffnen\"><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__4d9a6ea\" aria-expanded=\"true\" aria-label=\"Inhaltsverzeichnis schlie\u00dfen\"><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__4d9a6ea\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69c3d41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69c3d41\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-518e088\" data-id=\"518e088\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b4eae5 elementor-widget elementor-widget-text-editor\" data-id=\"3b4eae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Kniebeugen haben in den letzten Jahren wieder an Popularit\u00e4t gewonnen, da immer mehr Menschen ihre zahlreichen Vorteile entdeckt haben.<\/span><\/p><p>Dies \u00dcbung trainieren die gro\u00dfen Muskelgruppen, die f\u00fcr Sportler der Schl\u00fcssel zu mehr Kraft und St\u00e4rke sind und sie in die Lage versetzen, schneller zu laufen und h\u00f6her zu springen.<\/p><p>Sie kann dir helfen, Muskeln aufzubauen, Fett zu verlieren und deine Lebensqualit\u00e4t zu verbessern. Dennoch gibt es viele Mythen, die sich hartn\u00e4ckig halten &#8211; hier sind 10 von ihnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa18688 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa18688\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a6c9b3\" data-id=\"8a6c9b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd986c9 elementor-widget elementor-widget-heading\" data-id=\"fd986c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kniebeugen erh\u00f6hen die Knieelastizit\u00e4t.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58e5989 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58e5989\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e7d7dd\" data-id=\"2e7d7dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f0a806 elementor-widget elementor-widget-text-editor\" data-id=\"4f0a806\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1961 ver\u00f6ffentlichten der College-Professor Karl K. Klein und der Arzt Fred L. Allman Jr. eine Studie, in der sie behaupteten, dass volle tiefe der Kniebeuge- und nicht parallele Kniebeugen &#8211; die Knielockerung erh\u00f6hen und damit das Risiko von <a href=\"https:\/\/mainperformance.de\/vortiele-einer-trainierten-gesaessmuskulatur\/\">Knieverletzungen<\/a> steigern k\u00f6nnten.<\/p><p>Die Studie wies jedoch M\u00e4ngel auf, die Ergebnisse konnten nicht reproduziert werden, und sp\u00e4tere Studien ergaben, dass Personen, die volle Bewegung machten, stabilere Gelenke hatten als andere Bev\u00f6lkerungsgruppen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42161fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42161fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a83b36e\" data-id=\"a83b36e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0741856 elementor-widget elementor-widget-heading\" data-id=\"0741856\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kniebeugen verschlei\u00dfen die Gelenke.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbd9faa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbd9faa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd30984\" data-id=\"dd30984\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14e35eb elementor-widget elementor-widget-text-editor\" data-id=\"14e35eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>K\u00f6nnen dies \u00dcbung langfristige Sch\u00e4den an den Knien verursachen oder zu Arthritis f\u00fchren? Eine 2013 in der Fachzeitschrift Sports Medicine ver\u00f6ffentlichte Studie untersuchte das Risiko von <a href=\"https:\/\/mainperformance.de\/6-gruende-fuer-mehr-bewegung-im-alltag\/\">Verletzungen<\/a> und degenerativen Erkrankungen bei tiefen Kniebeugen.<\/p><p>Die Forscher kamen zu folgendem Schluss: &#8222;Bedenken \u00fcber degenerative Ver\u00e4nderungen des tendofemoralen Komplexes und das offensichtlich h\u00f6here Risiko f\u00fcr Chondromalazie, Arthrose und Osteochondritis bei der vollen Bewegung sind unbegr\u00fcndet.&#8220;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7056d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7056d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26fbd4f\" data-id=\"26fbd4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81f9b72 elementor-widget elementor-widget-heading\" data-id=\"81f9b72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Deadlifts sind genauso gut wie Kniebeugen. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3aa0d74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3aa0d74\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c91d5c9\" data-id=\"c91d5c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3897c35 elementor-widget elementor-widget-text-editor\" data-id=\"3897c35\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Kreuzheben trainiert nicht nur die wichtigsten Muskeln des <a href=\"https:\/\/mainperformance.de\/loesungen-duenne-menschen-und-muskeln-aufbauen\/\">Unterk\u00f6rpers<\/a>, sondern auch viele Muskeln des Oberk\u00f6rpers, wie den Trapezius und die Griffkraft.<\/p><p>Der Nachteil des Kreuzhebens besteht darin, dass die Beine nicht \u00fcber einen gro\u00dfen Bewegungsumfang beansprucht werden, so dass die Entwicklung der Quads und der Ges\u00e4\u00dfmuskeln nicht so ausgepr\u00e4gt ist, wie bei Kniebeugen. Entscheid dich nicht f\u00fcr das eine oder das andere, sondern nehme sowohl Kniebeugen als auch Kreuzheben in dein Programm auf.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ae7091 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ae7091\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ddf293\" data-id=\"0ddf293\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c3244 elementor-widget elementor-widget-heading\" data-id=\"98c3244\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kniebeugen machen dich langsam<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fff5887 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fff5887\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa2a0d9\" data-id=\"fa2a0d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c0dfa7 elementor-widget elementor-widget-text-editor\" data-id=\"9c0dfa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8222;<a href=\"https:\/\/mainperformance.de\/richtiges-trainingstempo\/\">Schnelligkeit<\/a> ist im Sport t\u00f6dlich&#8220;, und viele Trainer bef\u00fcrchten, dass eine zu starke Betonung der Kniebeuge die Athleten verlangsamen wird.<\/p><p>Viele Forschungsarbeiten haben diesen Mythos widerlegt. Ein Beispiel ist &#8222;Increases in Lower-Body Strength Transfer Positively to Sprint Performance: Eine systematische \u00dcberpr\u00fcfung mit Meta-Analyse&#8220;. In dieser Arbeit wurden 15 Studien mit insgesamt 510 Probanden untersucht, und 96 Prozent der Sprinttests (50 von 52) waren k\u00fcrzer als 30 Meter. Die Forscher kamen zu dem Schluss, dass &#8222;die Steigerung der Kraft im unteren K\u00f6rperbereich auf die Sprintleistung \u00fcbertragbar ist&#8220;.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98b5fa5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98b5fa5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-607c476\" data-id=\"607c476\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a907c3 elementor-widget elementor-widget-heading\" data-id=\"1a907c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pre-Exhaustion trainiert die Quads h\u00e4rter als Kniebeugen allein. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a95a4a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a95a4a5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0acd1e8\" data-id=\"0acd1e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df8a24b elementor-widget elementor-widget-text-editor\" data-id=\"df8a24b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Pre-Exhaustion ist eine Trainingsmethode, die 1968 von Robert Kennedy in der Bodybuilding-Welt eingef\u00fchrt und vom Nautilus-Gr\u00fcnder Arthur Jones popularisiert wurde.<\/span><\/div><p>Jones war der Ansicht, dass der begrenzende Faktor bei der Entwicklung der Quads durch Kniebeugen die St\u00e4rke des unteren R\u00fcckens ist. Daher empfahl er, die Quads vor der Kniebeuge mit Beinstreckern und Beinpressen &#8222;vorzubeanspruchen&#8220;. Netter Versuch.<\/p><p>Eine in der Mai-Ausgabe 2003 des Journal of Strength and Conditioning Research ver\u00f6ffentlichte Studie ergab, dass die Nachersch\u00f6pfung (d. h. die Ausf\u00fchrung der Haupt\u00fcbung zuerst) der Vorersch\u00f6pfung \u00fcberlegen ist.<\/p><p>Ein Grund daf\u00fcr ist, dass du, wenn du zuerst die isolierten Quad-Bewegungen ausf\u00fchrst, gezwungen bist, ein viel leichteres Gewicht zu verwenden, als du es sonst tun k\u00f6nntest, wodurch die Intensit\u00e4t der \u00dcbung verringert wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3abce4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3abce4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0164ca5\" data-id=\"0164ca5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e503724 elementor-widget elementor-widget-heading\" data-id=\"e503724\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teilkniebeugen sind besser f\u00fcr die Verbesserung des vertikalen Sprungs. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a58456 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a58456\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-413cd3e\" data-id=\"413cd3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c363eff elementor-widget elementor-widget-text-editor\" data-id=\"c363eff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da man am Ende einer <a href=\"https:\/\/mainperformance.de\/bessere-ergebnisse-mit-kniebeugen\/\">Kniebeuge<\/a> st\u00e4rker ist, wurde angenommen, dass eine Viertelhocke mit Maximalgewichten besser sind als volle Kniebeugen. Das stimmt nicht.<\/p><p>Eine deutsche Studie ergab, dass die volle Bewegung der Kniebeuge hingegen zu einer viertel Bewegung\u00a0 bei der Verbesserung des Vertikalsprungs \u00fcberlegen sind; die Gruppe, die volle Kniebeugen machte, verbesserte sich um 8 Prozent, w\u00e4hrend die Gruppe mit viertel Kniebeugen keine Verbesserung zeigte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ab8737 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ab8737\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa4d2ea\" data-id=\"aa4d2ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebd7f39 elementor-widget elementor-widget-heading\" data-id=\"ebd7f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die Knie sollten bei Kniebeugen niemals \u00fcber die Zehen hinausgehen. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8a1c91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8a1c91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d93f20\" data-id=\"7d93f20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6736d3 elementor-widget elementor-widget-text-editor\" data-id=\"b6736d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die \u00fcberwiegende Zahl der Untersuchungen hat gezeigt, dass &#8211; von wenigen Ausnahmen abgesehen (z. B. bei vorbestehenden Verletzungen) &#8211; Kniebeugen, bei denen die Knie vor den Zehen liegen, den Knien nicht schaden.<\/p><p>Interessant ist, dass diejenigen, die partielle Kniebeugen empfehlen, oft empfehlen, die Knie bei Ausfallschritten oder Split Squats nicht vor die Zehen gehen zu lassen. Ja, das vordere Bein kann man einschr\u00e4nken, aber was ist mit dem hinteren Bein?<\/p><p>In der Ausgangsposition der geteilten Hocke befindet sich das hintere Knie vor dem hinteren Fu\u00df, und die Vorw\u00e4rtsbewegung bei einem Ausfallschritt f\u00fchrt dazu, dass das hintere Knie sofort vor den hinteren Fu\u00df wandert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-889fd3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"889fd3a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7242d9\" data-id=\"f7242d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-414c4ad elementor-widget elementor-widget-heading\" data-id=\"414c4ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Powerlifting-Kniebeugen sind f\u00fcr Athleten besser als volle Kniebeugen. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfaa751 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfaa751\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-211238b\" data-id=\"211238b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2a9b41 elementor-widget elementor-widget-text-editor\" data-id=\"a2a9b41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diejenigen, die Powerlifting-Beugen gegen\u00fcber vollen Beugungen der Knie und der H\u00fcfte bef\u00fcrworten, haben starke Argumente, warum ihre \u00dcbung f\u00fcr Sportler besser ist.<\/p><p>Der Sportwissenschaftler Bud Charniga ist jedoch der Meinung, dass Methoden, die den Bewegungsumfang der Beine einschr\u00e4nken, wie z. B. die Durchf\u00fchrung von Teilbewegungen im Vergleich zu vollen Bewegungen, das Verletzungsrisiko erh\u00f6hen und die sportliche Leistung beeintr\u00e4chtigen k\u00f6nnen.<\/p><p>&#8222;Wenn du das Tapen von Kn\u00f6cheln und Knien, das Anlegen von Hosentr\u00e4gern und sogar das Versteifen von Schuhen, die Versteifung von Knien, H\u00fcften, Kn\u00f6chelgelenken, Sehnen und B\u00e4ndern mit Kniebeugen im Kraftdreikampf, Bankdr\u00fccken, Maschinen\u00fcbungen und so weiter kombinierst, was wird dann das Ergebnis sein? Wie werden sich die Gelenke auf nat\u00fcrliche Weise, proportional und im Verh\u00e4ltnis zueinander beugen k\u00f6nnen, und um wie viel?&#8220;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b1ef61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b1ef61\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-017e805\" data-id=\"017e805\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c943345 elementor-widget elementor-widget-heading\" data-id=\"c943345\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Man muss nicht tief in die Hocke gehen, um die Ges\u00e4\u00dfmuskulatur zu trainieren. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c28b080 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c28b080\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd4ec39\" data-id=\"cd4ec39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e14f60 elementor-widget elementor-widget-text-editor\" data-id=\"8e14f60\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn die Entwicklung der Ges\u00e4\u00dfmuskulatur eine Priorit\u00e4t ist, k\u00f6nntest du entt\u00e4uscht sein, wenn du keine vollen Kniebeugen machst. EMG-Forschungen haben ergeben, dass die volle tiefe die Ges\u00e4\u00dfmuskulatur um 100 % effektiver aktivieren als Teilbewegungen.<\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Die Kniebeuge war im letzten halben Jahrhundert eine verfolgte \u00dcbung, aber sie hat alle Kontroversen \u00fcberlebt, die durch Fehlinformationen verursacht wurden. Mythen werden sich immer hartn\u00e4ckig halten, aber bis jemand das Gegenteil beweist, ist die Kniebeuge immer noch der K\u00f6nig der Hebungen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-386f2d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"386f2d3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed2ce34\" data-id=\"ed2ce34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48a8353 elementor-widget elementor-widget-heading\" data-id=\"48a8353\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Referenzen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55e798ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55e798ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-698049c2\" data-id=\"698049c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a0eb075 elementor-widget elementor-widget-text-editor\" data-id=\"7a0eb075\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><div><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ); font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Augustsson, J. et al. Effect of pre-exhaustion exercise on lower-extremity muscle activation during a leg press exercise. J Strength Cond Res. 2003 May;17(2):411-6.<\/span><\/div><p>Bloomquist, K., et al. Effect of Range-of-Motion in Heavy Load Squatting on Muscle and Tendon Adaptations. European Journal of Applied Physiology. 2013 Aug. 113(8): 2133-42<\/p><p>Chandler T, Wilson G, and Stone M. The effect of the squat exercise on knee stability. Med Sci Sports Exerc 21: 299\u2013303, 1989.<\/p><p>Charniga, Bud. Practical solutions to the problem of Achilles rupture and the proliferation of injuries to the lower extremities of football players. Sportivny Press, February 14, 2107.<\/p><p>Gourgoulis, et all. Effect of a Submaximal Half-Squats Warm-up Program on Vertical Jumping Ability. J Strength Cond Res. 17(2):342-344, May 2003.<\/p><p>Hartmann, H., et al. Analysis of the load on the knee joint and vertebral column with changes in squatting depth and weight load. Sports Medicine. 2013, 43(10), 993-1008.<\/p><p>Hartmann, H., et al. Influence of Squatting Depth on Jumping Performance, Strength Cond Res 26 (12), 3243-3261.<\/p><p>Karl K. Klein, Fred L. Allman, Jr. The Knee in Sports, Penn State Press, 1971.<\/p><p>Seitz, L., et al. Increases in Lower-Body Strength Transfer Positively to Sprint Performance: A Systematic Review with Meta-Analysis, Sports Med, 44(12), 1693-170<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Inhaltsverzeichnis Kniebeugen haben in den letzten Jahren wieder an Popularit\u00e4t gewonnen, da immer mehr Menschen ihre zahlreichen Vorteile entdeckt haben. Dies \u00dcbung trainieren die gro\u00dfen Muskelgruppen, die f\u00fcr Sportler der Schl\u00fcssel zu mehr Kraft und St\u00e4rke sind und sie in die Lage versetzen, schneller zu laufen und h\u00f6her zu springen. Sie kann dir helfen, Muskeln [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[130,122,145,45,74,100],"class_list":["post-4974","post","type-post","status-publish","format-standard","hentry","category-training","tag-bewegung","tag-gesaess","tag-kniebeugen","tag-krafttraining","tag-muskelaufbau","tag-mythen"],"_links":{"self":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/4974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/comments?post=4974"}],"version-history":[{"count":0,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/posts\/4974\/revisions"}],"wp:attachment":[{"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/media?parent=4974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/categories?post=4974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mainperformance.de\/en\/wp-json\/wp\/v2\/tags?post=4974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}